{"id":127,"date":"2017-05-03T11:31:10","date_gmt":"2017-05-03T11:31:10","guid":{"rendered":"https:\/\/www.dimensioneazzurra.it\/?p=127"},"modified":"2017-07-04T06:35:24","modified_gmt":"2017-07-04T06:35:24","slug":"audio-post","status":"publish","type":"post","link":"https:\/\/www.dimensioneazzurra.it\/en\/2017\/05\/03\/audio-post\/","title":{"rendered":"Audio Post"},"content":{"rendered":"<p>Proin scelerisque consectetur nisl. Praesent tempus vitae metus quis tempor. Fusce nulla turpis, fermentum posuere luctus in, laoreet vel libero. In ultricies tortor vitae aliquet ultrices. Donec sit amet eleifend lorem, ac tempus turpis. Vivamus hendrerit, felis vitae porttitor auctor, velit augue tempor urna, in bibendum mi purus ac erat. Vivamus eu magna eu nulla semper tincidunt sit amet quis urna.<\/p>\n<p><!--more--><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-127-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.dimensioneazzurra.it\/wp-content\/uploads\/2017\/05\/sample-melody.mp3?_=1\" \/><a href=\"https:\/\/www.dimensioneazzurra.it\/wp-content\/uploads\/2017\/05\/sample-melody.mp3\">https:\/\/www.dimensioneazzurra.it\/wp-content\/uploads\/2017\/05\/sample-melody.mp3<\/a><\/audio>\n<p>Quisque a nulla feugiat, volutpat dolor ornare, sagittis dui. Curabitur vel tellus eu nulla feugiat vestibulum at id tortor. Suspendisse risus urna, aliquam ac finibus a, eleifend quis tellus. Maecenas at ultricies felis. Maecenas pharetra elementum erat, ac sollicitudin turpis euismod et. Aenean pellentesque arcu a tellus facilisis auctor. Suspendisse eu ipsum laoreet turpis semper fermentum nec at sapien. Nunc non libero cursus, egestas lacus vel, pellentesque lectus. Morbi eleifend turpis id elit aliquet, nec hendrerit ante aliquet.<\/p>","protected":false},"excerpt":{"rendered":"<p>Proin scelerisque consectetur nisl. Praesent tempus vitae metus quis tempor. Fusce nulla turpis, fermentum posuere luctus in, laoreet vel libero. In ultricies tortor vitae aliquet ultrices. Donec sit amet eleifend lorem, ac tempus turpis. Vivamus hendrerit, felis vitae porttitor auctor, velit augue tempor urna, in bibendum mi purus ac erat. Vivamus eu magna eu nulla semper tincidunt sit amet quis&hellip;<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"audio","meta":{"footnotes":""},"categories":[19,24],"tags":[28,29],"class_list":["post-127","post","type-post","status-publish","format-audio","hentry","category-anti-aging","category-media","tag-advice","tag-skin","post_format-post-format-audio"],"_links":{"self":[{"href":"https:\/\/www.dimensioneazzurra.it\/en\/wp-json\/wp\/v2\/posts\/127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dimensioneazzurra.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dimensioneazzurra.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dimensioneazzurra.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dimensioneazzurra.it\/en\/wp-json\/wp\/v2\/comments?post=127"}],"version-history":[{"count":0,"href":"https:\/\/www.dimensioneazzurra.it\/en\/wp-json\/wp\/v2\/posts\/127\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dimensioneazzurra.it\/en\/wp-json\/wp\/v2\/media?parent=127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dimensioneazzurra.it\/en\/wp-json\/wp\/v2\/categories?post=127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dimensioneazzurra.it\/en\/wp-json\/wp\/v2\/tags?post=127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}